{"id":214991,"date":"2021-02-24T09:50:11","date_gmt":"2021-02-24T08:50:11","guid":{"rendered":"https:\/\/zauner.at\/produkt\/osterschokolade-geschenkpackung\/"},"modified":"2026-04-03T12:11:50","modified_gmt":"2026-04-03T10:11:50","slug":"easter-chocolate-gift-box","status":"publish","type":"product","link":"https:\/\/zauner.at\/en\/produkt\/osterschokolade-geschenkpackung\/","title":{"rendered":"Easter Chocolate Gift Pack of 2"},"content":{"rendered":"<p>2 chocolate bars garnished with Easter motifs<\/p>\n<p>Lasts up to two months.<\/p>\n<p>Allergens: Soy (F), Nuts (H)<\/p>","protected":false},"excerpt":{"rendered":"<p>Finest nut-nougat chocolate in a 2-pack gift box, approx. 120 g<\/p>","protected":false},"featured_media":218673,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[117,113],"product_tag":[410,118,412,119,516,120,533,122,534,126,535,127,536,129,294,385,409],"class_list":{"0":"post-214991","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ostern","7":"product_cat-spezielle-anlaesse","8":"product_tag-osterhase","9":"product_tag-bad-ischl","10":"product_tag-ostern","11":"product_tag-dessert","12":"product_tag-verzierungen","13":"product_tag-geschenk","14":"product_tag-geschenkpackung-2er","15":"product_tag-konditorei-zauner","16":"product_tag-nuss-nougat-schokolade","17":"product_tag-pralinen","18":"product_tag-oesterlich","19":"product_tag-schokolade","20":"product_tag-zauner-osterschokolade","21":"product_tag-tradition","22":"product_tag-confiserie","23":"product_tag-suesswaren","24":"product_tag-osterei","26":"first","27":"outofstock","28":"taxable","29":"shipping-taxable","30":"purchasable","31":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Osterschokolade Geschenkpackung 2er - Zauner<\/title>\n<meta name=\"description\" content=\"Die perfekte Oster\u00fcberraschung! Die Zauner Osterschokolade Geschenkpackung begeistert mit feinster Schokolade &amp; edlem Design.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zauner.at\/en\/product-5\/easter-chocolate-gift-box\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Osterschokolade Geschenkpackung 2er - Zauner\" \/>\n<meta property=\"og:description\" content=\"Die perfekte Oster\u00fcberraschung! Die Zauner Osterschokolade Geschenkpackung begeistert mit feinster Schokolade &amp; edlem Design.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zauner.at\/en\/product-5\/easter-chocolate-gift-box\/\" \/>\n<meta property=\"og:site_name\" content=\"Zauner\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-03T10:11:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/Osterschokolade-Geschenkpackung.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"2400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/osterschokolade-geschenkpackung\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/osterschokolade-geschenkpackung\\\/\",\"name\":\"Osterschokolade Geschenkpackung 2er - Zauner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/osterschokolade-geschenkpackung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/osterschokolade-geschenkpackung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Osterschokolade-Geschenkpackung.jpg\",\"datePublished\":\"2021-02-24T08:50:11+00:00\",\"dateModified\":\"2026-04-03T10:11:50+00:00\",\"description\":\"Die perfekte Oster\u00fcberraschung! Die Zauner Osterschokolade Geschenkpackung begeistert mit feinster Schokolade & edlem Design.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/osterschokolade-geschenkpackung\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zauner.at\\\/produkt\\\/osterschokolade-geschenkpackung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/osterschokolade-geschenkpackung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Osterschokolade-Geschenkpackung.jpg\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Osterschokolade-Geschenkpackung.jpg\",\"width\":2400,\"height\":2400,\"caption\":\"Geschenkpackung mit zwei Tafeln Schokolade und \u00f6sterlichem Dekor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/osterschokolade-geschenkpackung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zauner.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unser Onlineshop\",\"item\":\"https:\\\/\\\/zauner.at\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Osterschokolade Geschenkpackung 2er\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"name\":\"Konditorei Zauner\",\"description\":\"Konditorei\",\"publisher\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zauner.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\",\"name\":\"Konditorei Zauner\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"width\":160,\"height\":142,\"caption\":\"Konditorei Zauner\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\\\/\",\"https:\\\/\\\/www.instagram.com\\\/zaunerkaffeekonditorei\\\/\",\"https:\\\/\\\/at.linkedin.com\\\/company\\\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Easter Chocolate Gift Pack of 2 - Zauner","description":"The perfect Easter surprise! The Zauner Easter chocolate gift pack delights with the finest chocolate and elegant design.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zauner.at\/en\/product-5\/easter-chocolate-gift-box\/","og_locale":"en_GB","og_type":"article","og_title":"Osterschokolade Geschenkpackung 2er - Zauner","og_description":"Die perfekte Oster\u00fcberraschung! Die Zauner Osterschokolade Geschenkpackung begeistert mit feinster Schokolade & edlem Design.","og_url":"https:\/\/zauner.at\/en\/product-5\/easter-chocolate-gift-box\/","og_site_name":"Zauner","article_publisher":"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","article_modified_time":"2026-04-03T10:11:50+00:00","og_image":[{"width":2400,"height":2400,"url":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/Osterschokolade-Geschenkpackung.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zauner.at\/produkt\/osterschokolade-geschenkpackung\/","url":"https:\/\/zauner.at\/produkt\/osterschokolade-geschenkpackung\/","name":"Easter Chocolate Gift Pack of 2 - Zauner","isPartOf":{"@id":"https:\/\/zauner.at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zauner.at\/produkt\/osterschokolade-geschenkpackung\/#primaryimage"},"image":{"@id":"https:\/\/zauner.at\/produkt\/osterschokolade-geschenkpackung\/#primaryimage"},"thumbnailUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/Osterschokolade-Geschenkpackung.jpg","datePublished":"2021-02-24T08:50:11+00:00","dateModified":"2026-04-03T10:11:50+00:00","description":"The perfect Easter surprise! The Zauner Easter chocolate gift pack delights with the finest chocolate and elegant design.","breadcrumb":{"@id":"https:\/\/zauner.at\/produkt\/osterschokolade-geschenkpackung\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zauner.at\/produkt\/osterschokolade-geschenkpackung\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/zauner.at\/produkt\/osterschokolade-geschenkpackung\/#primaryimage","url":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/Osterschokolade-Geschenkpackung.jpg","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/Osterschokolade-Geschenkpackung.jpg","width":2400,"height":2400,"caption":"Geschenkpackung mit zwei Tafeln Schokolade und \u00f6sterlichem Dekor"},{"@type":"BreadcrumbList","@id":"https:\/\/zauner.at\/produkt\/osterschokolade-geschenkpackung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zauner.at\/"},{"@type":"ListItem","position":2,"name":"Unser Onlineshop","item":"https:\/\/zauner.at\/shop\/"},{"@type":"ListItem","position":3,"name":"Osterschokolade Geschenkpackung 2er"}]},{"@type":"WebSite","@id":"https:\/\/zauner.at\/#website","url":"https:\/\/zauner.at\/","name":"Konditorei Zauner","description":"pastry shop","publisher":{"@id":"https:\/\/zauner.at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zauner.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/zauner.at\/#organization","name":"Konditorei Zauner","url":"https:\/\/zauner.at\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/","url":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","width":160,"height":142,"caption":"Konditorei Zauner"},"image":{"@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","https:\/\/www.instagram.com\/zaunerkaffeekonditorei\/","https:\/\/at.linkedin.com\/company\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header"]}]}},"_links":{"self":[{"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/product\/214991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/comments?post=214991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/media\/218673"}],"wp:attachment":[{"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/media?parent=214991"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/product_brand?post=214991"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/product_cat?post=214991"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/product_tag?post=214991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}