{"id":213726,"date":"2011-07-19T08:44:56","date_gmt":"2011-07-19T06:44:56","guid":{"rendered":"https:\/\/zauner.at\/produkt\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\/"},"modified":"2026-08-24T11:08:44","modified_gmt":"2026-08-24T09:08:44","slug":"zauner-torte-cremechocolat-truffle-15cm-diameter","status":"publish","type":"product","link":"https:\/\/zauner.at\/en\/produkt\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\/","title":{"rendered":"Cream chocolate truffle cake"},"content":{"rendered":"<p>A comfortable world of stylish enjoyment is rounded off in perfect harmony.<\/p>\n<p>For all those who love to celebrate even the smallest event in a big way.<\/p>\n<p>For immediate consumption!<\/p>\n<p>Allergens: Gluten (A), Egg (C), Soy (F), Milk (G), Nuts (H)<\/p>","protected":false},"excerpt":{"rendered":"<p>Sacher torte filled with fine Parisian cream, covered with marzipan and milk chocolate, with a diameter of 15 cm, approx. 450 g<\/p>","protected":false},"featured_media":217637,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[95,96],"product_tag":[274,275,276,122,130,152,153,273],"class_list":["post-213726","product","type-product","status-publish","has-post-thumbnail","product_cat-kleintorten","product_cat-torten-backwaren","product_tag-schokoladencreme","product_tag-tortenpraesent","product_tag-trueffeltorte","product_tag-konditorei-zauner","product_tag-trueffel","product_tag-torte","product_tag-versandtorte","product_tag-kleintorte","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cremechocolat Tr\u00fcffel Torte<\/title>\n<meta name=\"description\" content=\"Die Zauner Cremechocolat Tr\u00fcffel-Torte \u2013 zart, cremig &amp; schokoladig. Jetzt bestellen &amp; pure Konditorenkunst genie\u00dfen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zauner.at\/en\/product-5\/zauner-torte-cremechocolat-truffle-15cm-diameter\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cremechocolat Tr\u00fcffel Torte\" \/>\n<meta property=\"og:description\" content=\"Die Zauner Cremechocolat Tr\u00fcffel-Torte \u2013 zart, cremig &amp; schokoladig. Jetzt bestellen &amp; pure Konditorenkunst genie\u00dfen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zauner.at\/en\/product-5\/zauner-torte-cremechocolat-truffle-15cm-diameter\/\" \/>\n<meta property=\"og:site_name\" content=\"Zauner\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-24T09:08:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/konditorei-zauner-produkt-torten-backwaren-kleintorte-cremechocolat-trueffel-torte-1200x1200-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\\\/\",\"name\":\"Cremechocolat Tr\u00fcffel Torte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/konditorei-zauner-produkt-torten-backwaren-kleintorte-cremechocolat-trueffel-torte-1200x1200-1.jpg\",\"datePublished\":\"2011-07-19T06:44:56+00:00\",\"dateModified\":\"2026-08-24T09:08:44+00:00\",\"description\":\"Die Zauner Cremechocolat Tr\u00fcffel-Torte \u2013 zart, cremig & schokoladig. Jetzt bestellen & pure Konditorenkunst genie\u00dfen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zauner.at\\\/produkt\\\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/konditorei-zauner-produkt-torten-backwaren-kleintorte-cremechocolat-trueffel-torte-1200x1200-1.jpg\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/konditorei-zauner-produkt-torten-backwaren-kleintorte-cremechocolat-trueffel-torte-1200x1200-1.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Zauner Cremechocolat-Tr\u00fcffeltorte im Geschenkkarton\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zauner.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unser Onlineshop\",\"item\":\"https:\\\/\\\/zauner.at\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cremechocolat Tr\u00fcffel Torte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"name\":\"Konditorei Zauner\",\"description\":\"Konditorei\",\"publisher\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zauner.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\",\"name\":\"Konditorei Zauner\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"width\":160,\"height\":142,\"caption\":\"Konditorei Zauner\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\\\/\",\"https:\\\/\\\/www.instagram.com\\\/zaunerkaffeekonditorei\\\/\",\"https:\\\/\\\/at.linkedin.com\\\/company\\\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cream chocolate truffle cake","description":"The Zauner Cremechocolat truffle cake \u2013 tender, creamy &amp; chocolaty. Order now and enjoy pure confectionery art!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zauner.at\/en\/product-5\/zauner-torte-cremechocolat-truffle-15cm-diameter\/","og_locale":"en_GB","og_type":"article","og_title":"Cremechocolat Tr\u00fcffel Torte","og_description":"Die Zauner Cremechocolat Tr\u00fcffel-Torte \u2013 zart, cremig & schokoladig. Jetzt bestellen & pure Konditorenkunst genie\u00dfen!","og_url":"https:\/\/zauner.at\/en\/product-5\/zauner-torte-cremechocolat-truffle-15cm-diameter\/","og_site_name":"Zauner","article_publisher":"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","article_modified_time":"2026-08-24T09:08:44+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/konditorei-zauner-produkt-torten-backwaren-kleintorte-cremechocolat-trueffel-torte-1200x1200-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zauner.at\/produkt\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\/","url":"https:\/\/zauner.at\/produkt\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\/","name":"Cream chocolate truffle cake","isPartOf":{"@id":"https:\/\/zauner.at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zauner.at\/produkt\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\/#primaryimage"},"image":{"@id":"https:\/\/zauner.at\/produkt\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\/#primaryimage"},"thumbnailUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/konditorei-zauner-produkt-torten-backwaren-kleintorte-cremechocolat-trueffel-torte-1200x1200-1.jpg","datePublished":"2011-07-19T06:44:56+00:00","dateModified":"2026-08-24T09:08:44+00:00","description":"The Zauner Cremechocolat truffle cake \u2013 tender, creamy &amp; chocolaty. Order now and enjoy pure confectionery art!","breadcrumb":{"@id":"https:\/\/zauner.at\/produkt\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zauner.at\/produkt\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/zauner.at\/produkt\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\/#primaryimage","url":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/konditorei-zauner-produkt-torten-backwaren-kleintorte-cremechocolat-trueffel-torte-1200x1200-1.jpg","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/konditorei-zauner-produkt-torten-backwaren-kleintorte-cremechocolat-trueffel-torte-1200x1200-1.jpg","width":1200,"height":1200,"caption":"Zauner Cremechocolat-Tr\u00fcffeltorte im Geschenkkarton"},{"@type":"BreadcrumbList","@id":"https:\/\/zauner.at\/produkt\/zauner-torte-cremechocolat-truffel-15cm-durchmesser\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zauner.at\/"},{"@type":"ListItem","position":2,"name":"Unser Onlineshop","item":"https:\/\/zauner.at\/shop\/"},{"@type":"ListItem","position":3,"name":"Cremechocolat Tr\u00fcffel Torte"}]},{"@type":"WebSite","@id":"https:\/\/zauner.at\/#website","url":"https:\/\/zauner.at\/","name":"Konditorei Zauner","description":"pastry shop","publisher":{"@id":"https:\/\/zauner.at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zauner.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/zauner.at\/#organization","name":"Konditorei Zauner","url":"https:\/\/zauner.at\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/","url":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","width":160,"height":142,"caption":"Konditorei Zauner"},"image":{"@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","https:\/\/www.instagram.com\/zaunerkaffeekonditorei\/","https:\/\/at.linkedin.com\/company\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header"]}]}},"_links":{"self":[{"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/product\/213726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/comments?post=213726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/media\/217637"}],"wp:attachment":[{"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/media?parent=213726"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/product_brand?post=213726"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/product_cat?post=213726"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zauner.at\/en\/wp-json\/wp\/v2\/product_tag?post=213726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}