{"id":108,"count":5,"description":"","link":"https:\/\/zauner.at\/cz\/produkt-kategorie\/geschenke-gutscheine\/buecher\/","name":"knihy","slug":"knihy","taxonomy":"product_cat","parent":107,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>B\u00fccher Archive - Zauner<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B\u00fccher Archive - Zauner\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zauner.at\/cz\/product-category\/darkove-poukazy\/knihy\/\" \/>\n<meta property=\"og:site_name\" content=\"Zauner\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zauner.at\/wp-content\/uploads\/2025\/01\/zauner-konditorei-cafe-hero-28424693_1591881217516353_6705677175667134588_o_web-890x590-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"890\" \/>\n\t<meta property=\"og:image:height\" content=\"591\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt-kategorie\\\/geschenke-gutscheine\\\/buecher\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/produkt-kategorie\\\/geschenke-gutscheine\\\/buecher\\\/\",\"name\":\"B\u00fccher Archive - Zauner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt-kategorie\\\/geschenke-gutscheine\\\/buecher\\\/#breadcrumb\"},\"inLanguage\":\"cs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt-kategorie\\\/geschenke-gutscheine\\\/buecher\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zauner.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Geschenke &amp; Gutscheine\",\"item\":\"https:\\\/\\\/zauner.at\\\/produkt-kategorie\\\/geschenke-gutscheine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"B\u00fccher\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"name\":\"Konditorei Zauner\",\"description\":\"Konditorei\",\"publisher\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zauner.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\",\"name\":\"Konditorei Zauner\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"width\":160,\"height\":142,\"caption\":\"Konditorei Zauner\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\\\/\",\"https:\\\/\\\/www.instagram.com\\\/zaunerkaffeekonditorei\\\/\",\"https:\\\/\\\/at.linkedin.com\\\/company\\\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archiv knih - Zauner","robots":{"index":"noindex","follow":"follow"},"og_locale":"cs_CZ","og_type":"article","og_title":"B\u00fccher Archive - Zauner","og_url":"https:\/\/zauner.at\/cz\/product-category\/darkove-poukazy\/knihy\/","og_site_name":"Zauner","og_image":[{"width":890,"height":591,"url":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/01\/zauner-konditorei-cafe-hero-28424693_1591881217516353_6705677175667134588_o_web-890x590-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/zauner.at\/produkt-kategorie\/geschenke-gutscheine\/buecher\/","url":"https:\/\/zauner.at\/produkt-kategorie\/geschenke-gutscheine\/buecher\/","name":"Archiv knih - Zauner","isPartOf":{"@id":"https:\/\/zauner.at\/#website"},"breadcrumb":{"@id":"https:\/\/zauner.at\/produkt-kategorie\/geschenke-gutscheine\/buecher\/#breadcrumb"},"inLanguage":"cs"},{"@type":"BreadcrumbList","@id":"https:\/\/zauner.at\/produkt-kategorie\/geschenke-gutscheine\/buecher\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zauner.at\/"},{"@type":"ListItem","position":2,"name":"Geschenke &amp; Gutscheine","item":"https:\/\/zauner.at\/produkt-kategorie\/geschenke-gutscheine\/"},{"@type":"ListItem","position":3,"name":"B\u00fccher"}]},{"@type":"WebSite","@id":"https:\/\/zauner.at\/#website","url":"https:\/\/zauner.at\/","name":"Cukr\u00e1rna Zauner","description":"Cukrovinky","publisher":{"@id":"https:\/\/zauner.at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zauner.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/zauner.at\/#organization","name":"Cukr\u00e1rna Zauner","url":"https:\/\/zauner.at\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/","url":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","width":160,"height":142,"caption":"Konditorei Zauner"},"image":{"@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","https:\/\/www.instagram.com\/zaunerkaffeekonditorei\/","https:\/\/at.linkedin.com\/company\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header"]}]}},"_links":{"self":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_cat\/108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_cat\/107"}],"wp:post_type":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product?product_cat=108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}