{"id":222152,"date":"2025-09-23T14:34:06","date_gmt":"2025-09-23T12:34:06","guid":{"rendered":"https:\/\/zauner.at\/produkt\/weihnachtliche-trueffelstange-creme\/"},"modified":"2026-02-02T08:18:48","modified_gmt":"2026-02-02T07:18:48","slug":"weihnachtliche-trueffelstange-creme","status":"publish","type":"product","link":"https:\/\/zauner.at\/cz\/produkt\/weihnachtliche-trueffelstange-creme\/","title":{"rendered":"Weihnachtliche Tr\u00fcffelstange &#8220;Creme&#8221;"},"content":{"rendered":"<p>Edle Tr\u00fcffelkugeln in festlicher Weihnachtsverpackung.<\/p>\n<p>K dispozici v r\u016fzn\u00fdch velikostech.<\/p>\n<p><a href=\"https:\/\/zauner.at\/cz\/trueffel-und-pralinen-vom-zauner\/\">\u00dcberzeugen Sie sich hier von unserem Confiserie-Sortiment!<\/a><\/p>\n<p>Trvanlivost a\u017e dva m\u011bs\u00edce.<\/p>\n<p>Alergeny: Lepek (A), Vejce (C), S\u00f3ja (F), Ml\u00e9ko (G), O\u0159echy (H)<\/p>","protected":false},"excerpt":{"rendered":"<p>Feinste handgefertigte Tr\u00fcffelkugeln in edler Weihnachtsverpackung<\/p>","protected":false},"featured_media":222155,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[115,264,113],"product_tag":[330,334,118,335,120,430,122,431,126,434,127,471,130,143,294],"class_list":{"0":"post-222152","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-weihnachten","7":"product_cat-weihnachtsconfiserie","8":"product_cat-spezielle-anlaesse","9":"product_tag-hofzuckerbaeckerei","10":"product_tag-onlineshop","11":"product_tag-bad-ischl","12":"product_tag-salzkammergut","13":"product_tag-geschenk","14":"product_tag-advent","15":"product_tag-konditorei-zauner","16":"product_tag-weihnachten","17":"product_tag-pralinen","18":"product_tag-trueffelkugeln","19":"product_tag-schokolade","20":"product_tag-trueffelstange","21":"product_tag-trueffel","22":"product_tag-zauner-bad-ischl","23":"product_tag-confiserie","25":"first","26":"outofstock","27":"taxable","28":"shipping-taxable","29":"purchasable","30":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weihnachtliche Tr\u00fcffelstange &quot;Creme&quot; - Zauner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zauner.at\/cz\/product-2\/weihnachtliche-trueffelstange-creme\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weihnachtliche Tr\u00fcffelstange &quot;Creme&quot; - Zauner\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zauner.at\/cz\/product-2\/weihnachtliche-trueffelstange-creme\/\" \/>\n<meta property=\"og:site_name\" content=\"Zauner\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T07:18:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zauner.at\/wp-content\/uploads\/2025\/09\/Trueffelstange-Creme-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/weihnachtliche-trueffelstange-creme\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/weihnachtliche-trueffelstange-creme\\\/\",\"name\":\"Weihnachtliche Tr\u00fcffelstange \\\"Creme\\\" - Zauner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/weihnachtliche-trueffelstange-creme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/weihnachtliche-trueffelstange-creme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Trueffelstange-Creme-scaled.jpg\",\"datePublished\":\"2025-09-23T12:34:06+00:00\",\"dateModified\":\"2026-02-02T07:18:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/weihnachtliche-trueffelstange-creme\\\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zauner.at\\\/produkt\\\/weihnachtliche-trueffelstange-creme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/weihnachtliche-trueffelstange-creme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Trueffelstange-Creme-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Trueffelstange-Creme-scaled.jpg\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/weihnachtliche-trueffelstange-creme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zauner.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unser Onlineshop\",\"item\":\"https:\\\/\\\/zauner.at\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Weihnachtliche Tr\u00fcffelstange &#8220;Creme&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"name\":\"Konditorei Zauner\",\"description\":\"Konditorei\",\"publisher\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zauner.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\",\"name\":\"Konditorei Zauner\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"width\":160,\"height\":142,\"caption\":\"Konditorei Zauner\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\\\/\",\"https:\\\/\\\/www.instagram.com\\\/zaunerkaffeekonditorei\\\/\",\"https:\\\/\\\/at.linkedin.com\\\/company\\\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weihnachtliche Tr\u00fcffelstange \"Creme\" - Zauner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zauner.at\/cz\/product-2\/weihnachtliche-trueffelstange-creme\/","og_locale":"cs_CZ","og_type":"article","og_title":"Weihnachtliche Tr\u00fcffelstange \"Creme\" - Zauner","og_url":"https:\/\/zauner.at\/cz\/product-2\/weihnachtliche-trueffelstange-creme\/","og_site_name":"Zauner","article_publisher":"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","article_modified_time":"2026-02-02T07:18:48+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/09\/Trueffelstange-Creme-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zauner.at\/produkt\/weihnachtliche-trueffelstange-creme\/","url":"https:\/\/zauner.at\/produkt\/weihnachtliche-trueffelstange-creme\/","name":"Weihnachtliche Tr\u00fcffelstange \"Creme\" - Zauner","isPartOf":{"@id":"https:\/\/zauner.at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zauner.at\/produkt\/weihnachtliche-trueffelstange-creme\/#primaryimage"},"image":{"@id":"https:\/\/zauner.at\/produkt\/weihnachtliche-trueffelstange-creme\/#primaryimage"},"thumbnailUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/09\/Trueffelstange-Creme-scaled.jpg","datePublished":"2025-09-23T12:34:06+00:00","dateModified":"2026-02-02T07:18:48+00:00","breadcrumb":{"@id":"https:\/\/zauner.at\/produkt\/weihnachtliche-trueffelstange-creme\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zauner.at\/produkt\/weihnachtliche-trueffelstange-creme\/"]}]},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zauner.at\/produkt\/weihnachtliche-trueffelstange-creme\/#primaryimage","url":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/09\/Trueffelstange-Creme-scaled.jpg","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/09\/Trueffelstange-Creme-scaled.jpg","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/zauner.at\/produkt\/weihnachtliche-trueffelstange-creme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zauner.at\/"},{"@type":"ListItem","position":2,"name":"Unser Onlineshop","item":"https:\/\/zauner.at\/shop\/"},{"@type":"ListItem","position":3,"name":"Weihnachtliche Tr\u00fcffelstange &#8220;Creme&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/zauner.at\/#website","url":"https:\/\/zauner.at\/","name":"Cukr\u00e1rna Zauner","description":"Cukrovinky","publisher":{"@id":"https:\/\/zauner.at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zauner.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/zauner.at\/#organization","name":"Cukr\u00e1rna Zauner","url":"https:\/\/zauner.at\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/","url":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","width":160,"height":142,"caption":"Konditorei Zauner"},"image":{"@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","https:\/\/www.instagram.com\/zaunerkaffeekonditorei\/","https:\/\/at.linkedin.com\/company\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header"]}]}},"_links":{"self":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product\/222152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/comments?post=222152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/media\/222155"}],"wp:attachment":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/media?parent=222152"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_brand?post=222152"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_cat?post=222152"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_tag?post=222152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}