{"id":215386,"date":"2022-02-24T07:29:22","date_gmt":"2022-02-24T06:29:22","guid":{"rendered":"https:\/\/zauner.at\/produkt\/zauner-geschenkkarton-zauner-spezialitaeten\/"},"modified":"2026-05-04T08:10:12","modified_gmt":"2026-05-04T06:10:12","slug":"zauner-geschenkkarton-zauner-spezialitaeten","status":"publish","type":"product","link":"https:\/\/zauner.at\/cz\/produkt\/zauner-geschenkkarton-zauner-spezialitaeten\/","title":{"rendered":"Geschenkkarton &#8220;Zauner Spezialit\u00e4ten&#8221;"},"content":{"rendered":"<p>Ein besonderes Geschenk gef\u00fcllt mit den beliebtesten Spezialit\u00e4ten aus dem Hause Zauner<\/p>\n<p>1 x Zaunerstollen Gr. I, 145 g<br \/>\n1 x Zaunerstollenlik\u00f6r, 200 ml<br \/>\n1 x Zauner Oblaten, 10-St\u00fcck-Dose, 250 g<br \/>\n1 x Zauner Ischler T\u00f6rtchen, 5-St\u00fcck-Packung<br \/>\n1 x Zauner Kaiserdessert<br \/>\n1 x Zauner Schichtennougatpralinen, 18 St\u00fcck, 180 g<\/p>\n<p>Allergene: Gluten (A), Ei (C), Erdnuss (E), Soja (F), Laktose (M), Schalenfr\u00fcchte (H)<\/p>","protected":false},"excerpt":{"rendered":"<p>Ein besonderes Geschenk gef\u00fcllt mit den beliebtesten Spezialit\u00e4ten aus dem Hause Zauner<\/p>","protected":false},"featured_media":217597,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[100,102,107,109],"product_tag":[127,130,132,143,154,337,736,122,126],"class_list":{"0":"post-215386","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pralinen-confiserie","7":"product_cat-pralinen-konfekt","8":"product_cat-geschenke-gutscheine","9":"product_cat-geschenksets","10":"product_tag-schokolade","11":"product_tag-trueffel","12":"product_tag-zaunerstollen","13":"product_tag-zauner-bad-ischl","14":"product_tag-zauner","15":"product_tag-schokoladentafel","16":"product_tag-spezialitaeten","17":"product_tag-konditorei-zauner","18":"product_tag-pralinen","20":"first","21":"instock","22":"taxable","23":"shipping-taxable","24":"purchasable","25":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Geschenkkarton &quot;Zauner Spezialit\u00e4ten&quot; - Zauner<\/title>\n<meta name=\"description\" content=\"Der Zauner Geschenkkarton \u2013 gef\u00fcllt mit exquisiten Spezialit\u00e4ten. Perfekt als s\u00fc\u00dfes Geschenk f\u00fcr Genie\u00dfer! Jetzt bestellen &amp; Freude bereiten!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zauner.at\/cz\/product-2\/zauner-geschenkkarton-zauner-spezialitaeten\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geschenkkarton &quot;Zauner Spezialit\u00e4ten&quot; - Zauner\" \/>\n<meta property=\"og:description\" content=\"Der Zauner Geschenkkarton \u2013 gef\u00fcllt mit exquisiten Spezialit\u00e4ten. Perfekt als s\u00fc\u00dfes Geschenk f\u00fcr Genie\u00dfer! Jetzt bestellen &amp; Freude bereiten!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zauner.at\/cz\/product-2\/zauner-geschenkkarton-zauner-spezialitaeten\/\" \/>\n<meta property=\"og:site_name\" content=\"Zauner\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T06:10:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zauner.at\/wp-content\/uploads\/2022\/02\/konditorei-zauner-produkt-geschenke-geschenkkarton-zauner-spez-1200x1200-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/zauner-geschenkkarton-zauner-spezialitaeten\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/zauner-geschenkkarton-zauner-spezialitaeten\\\/\",\"name\":\"Geschenkkarton \\\"Zauner Spezialit\u00e4ten\\\" - Zauner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/zauner-geschenkkarton-zauner-spezialitaeten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/zauner-geschenkkarton-zauner-spezialitaeten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/konditorei-zauner-produkt-geschenke-geschenkkarton-zauner-spez-1200x1200-1.jpg\",\"datePublished\":\"2022-02-24T06:29:22+00:00\",\"dateModified\":\"2026-05-04T06:10:12+00:00\",\"description\":\"Der Zauner Geschenkkarton \u2013 gef\u00fcllt mit exquisiten Spezialit\u00e4ten. Perfekt als s\u00fc\u00dfes Geschenk f\u00fcr Genie\u00dfer! Jetzt bestellen & Freude bereiten!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/zauner-geschenkkarton-zauner-spezialitaeten\\\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zauner.at\\\/produkt\\\/zauner-geschenkkarton-zauner-spezialitaeten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/zauner-geschenkkarton-zauner-spezialitaeten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/konditorei-zauner-produkt-geschenke-geschenkkarton-zauner-spez-1200x1200-1.jpg\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/konditorei-zauner-produkt-geschenke-geschenkkarton-zauner-spez-1200x1200-1.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Zauner Geschenkkarton \\\"Zauner Spezialit\u00e4ten\\\" u.a. mit Zaunerstollen, Ischler T\u00f6rtchen und Oblaten\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/zauner-geschenkkarton-zauner-spezialitaeten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zauner.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unser Onlineshop\",\"item\":\"https:\\\/\\\/zauner.at\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Geschenkkarton &#8220;Zauner Spezialit\u00e4ten&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"name\":\"Konditorei Zauner\",\"description\":\"Konditorei\",\"publisher\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zauner.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\",\"name\":\"Konditorei Zauner\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"width\":160,\"height\":142,\"caption\":\"Konditorei Zauner\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\\\/\",\"https:\\\/\\\/www.instagram.com\\\/zaunerkaffeekonditorei\\\/\",\"https:\\\/\\\/at.linkedin.com\\\/company\\\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geschenkkarton \"Zauner Spezialit\u00e4ten\" - Zauner","description":"Der Zauner Geschenkkarton \u2013 gef\u00fcllt mit exquisiten Spezialit\u00e4ten. Perfekt als s\u00fc\u00dfes Geschenk f\u00fcr Genie\u00dfer! Jetzt bestellen & Freude bereiten!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zauner.at\/cz\/product-2\/zauner-geschenkkarton-zauner-spezialitaeten\/","og_locale":"cs_CZ","og_type":"article","og_title":"Geschenkkarton \"Zauner Spezialit\u00e4ten\" - Zauner","og_description":"Der Zauner Geschenkkarton \u2013 gef\u00fcllt mit exquisiten Spezialit\u00e4ten. Perfekt als s\u00fc\u00dfes Geschenk f\u00fcr Genie\u00dfer! Jetzt bestellen & Freude bereiten!","og_url":"https:\/\/zauner.at\/cz\/product-2\/zauner-geschenkkarton-zauner-spezialitaeten\/","og_site_name":"Zauner","article_publisher":"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","article_modified_time":"2026-05-04T06:10:12+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/zauner.at\/wp-content\/uploads\/2022\/02\/konditorei-zauner-produkt-geschenke-geschenkkarton-zauner-spez-1200x1200-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zauner.at\/produkt\/zauner-geschenkkarton-zauner-spezialitaeten\/","url":"https:\/\/zauner.at\/produkt\/zauner-geschenkkarton-zauner-spezialitaeten\/","name":"Geschenkkarton \"Zauner Spezialit\u00e4ten\" - Zauner","isPartOf":{"@id":"https:\/\/zauner.at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zauner.at\/produkt\/zauner-geschenkkarton-zauner-spezialitaeten\/#primaryimage"},"image":{"@id":"https:\/\/zauner.at\/produkt\/zauner-geschenkkarton-zauner-spezialitaeten\/#primaryimage"},"thumbnailUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2022\/02\/konditorei-zauner-produkt-geschenke-geschenkkarton-zauner-spez-1200x1200-1.jpg","datePublished":"2022-02-24T06:29:22+00:00","dateModified":"2026-05-04T06:10:12+00:00","description":"Der Zauner Geschenkkarton \u2013 gef\u00fcllt mit exquisiten Spezialit\u00e4ten. Perfekt als s\u00fc\u00dfes Geschenk f\u00fcr Genie\u00dfer! Jetzt bestellen & Freude bereiten!","breadcrumb":{"@id":"https:\/\/zauner.at\/produkt\/zauner-geschenkkarton-zauner-spezialitaeten\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zauner.at\/produkt\/zauner-geschenkkarton-zauner-spezialitaeten\/"]}]},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zauner.at\/produkt\/zauner-geschenkkarton-zauner-spezialitaeten\/#primaryimage","url":"https:\/\/zauner.at\/wp-content\/uploads\/2022\/02\/konditorei-zauner-produkt-geschenke-geschenkkarton-zauner-spez-1200x1200-1.jpg","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2022\/02\/konditorei-zauner-produkt-geschenke-geschenkkarton-zauner-spez-1200x1200-1.jpg","width":1200,"height":1200,"caption":"Zauner Geschenkkarton \"Zauner Spezialit\u00e4ten\" u.a. mit Zaunerstollen, Ischler T\u00f6rtchen und Oblaten"},{"@type":"BreadcrumbList","@id":"https:\/\/zauner.at\/produkt\/zauner-geschenkkarton-zauner-spezialitaeten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zauner.at\/"},{"@type":"ListItem","position":2,"name":"Unser Onlineshop","item":"https:\/\/zauner.at\/shop\/"},{"@type":"ListItem","position":3,"name":"Geschenkkarton &#8220;Zauner Spezialit\u00e4ten&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/zauner.at\/#website","url":"https:\/\/zauner.at\/","name":"Cukr\u00e1rna Zauner","description":"Cukrovinky","publisher":{"@id":"https:\/\/zauner.at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zauner.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/zauner.at\/#organization","name":"Cukr\u00e1rna Zauner","url":"https:\/\/zauner.at\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/","url":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","width":160,"height":142,"caption":"Konditorei Zauner"},"image":{"@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","https:\/\/www.instagram.com\/zaunerkaffeekonditorei\/","https:\/\/at.linkedin.com\/company\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header"]}]}},"_links":{"self":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product\/215386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/comments?post=215386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/media\/217597"}],"wp:attachment":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/media?parent=215386"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_brand?post=215386"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_cat?post=215386"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_tag?post=215386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}