{"id":213893,"date":"2011-09-08T11:36:49","date_gmt":"2011-09-08T09:36:49","guid":{"rendered":"https:\/\/zauner.at\/produkt\/englischer-teekuchen\/"},"modified":"2026-05-11T10:13:49","modified_gmt":"2026-05-11T08:13:49","slug":"englischer-teekuchen","status":"publish","type":"product","link":"https:\/\/zauner.at\/cz\/produkt\/englischer-teekuchen\/","title":{"rendered":"Englischer Teekuchen"},"content":{"rendered":"<p>Eine saftige Bisquitmasse mit reichlich kandierten Fr\u00fcchten und Rosinen, umh\u00fcllt von einer zarten Schicht Marillenmarmelade und flaumigen Bisquit.<\/p>\n<p>Bis zu zwei Wochen haltbar.<\/p>\n<p>Allergene: Gluten (A), Ei (C), Milch (G), N\u00fcsse (H), Sulfite (O)<\/p>","protected":false},"excerpt":{"rendered":"<p>Saftige Bisquitmasse mit kandierten Fr\u00fcchten, ca. 500 g<\/p>","protected":false},"featured_media":211531,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[96,97],"product_tag":[619,620,621,622,122,143,284,315,378,617,618],"class_list":{"0":"post-213893","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-torten-backwaren","7":"product_cat-kuchen","8":"product_tag-klassiker","9":"product_tag-marillenmarmelade","10":"product_tag-rosinen","11":"product_tag-teekuchen","12":"product_tag-konditorei-zauner","13":"product_tag-zauner-bad-ischl","14":"product_tag-kaffeegebaeck","15":"product_tag-kuchen","16":"product_tag-kandierte-fruechte","17":"product_tag-bisquitmasse","18":"product_tag-englischer-teekuchen","20":"first","21":"instock","22":"taxable","23":"shipping-taxable","24":"purchasable","25":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Englischer Teekuchen - fruchtig und aromatisch<\/title>\n<meta name=\"description\" content=\"Genie\u00dfen Sie den Englischen Teekuchen von Zauner \u2013 saftig, fruchtig und mit feinsten Zutaten gebacken. Perfekt zum Tee oder Kaffee!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zauner.at\/cz\/product-2\/englischer-teekuchen\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Englischer Teekuchen - fruchtig und aromatisch\" \/>\n<meta property=\"og:description\" content=\"Genie\u00dfen Sie den Englischen Teekuchen von Zauner \u2013 saftig, fruchtig und mit feinsten Zutaten gebacken. Perfekt zum Tee oder Kaffee!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zauner.at\/cz\/product-2\/englischer-teekuchen\/\" \/>\n<meta property=\"og:site_name\" content=\"Zauner\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T08:13:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zauner.at\/wp-content\/uploads\/2024\/09\/Englischer-Teekuchen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/englischer-teekuchen\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/englischer-teekuchen\\\/\",\"name\":\"Englischer Teekuchen - fruchtig und aromatisch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/englischer-teekuchen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/englischer-teekuchen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Englischer-Teekuchen.jpg\",\"datePublished\":\"2011-09-08T09:36:49+00:00\",\"dateModified\":\"2026-05-11T08:13:49+00:00\",\"description\":\"Genie\u00dfen Sie den Englischen Teekuchen von Zauner \u2013 saftig, fruchtig und mit feinsten Zutaten gebacken. Perfekt zum Tee oder Kaffee!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/englischer-teekuchen\\\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zauner.at\\\/produkt\\\/englischer-teekuchen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/englischer-teekuchen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Englischer-Teekuchen.jpg\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Englischer-Teekuchen.jpg\",\"width\":1600,\"height\":1600,\"caption\":\"Englischer Teekuchen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/englischer-teekuchen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zauner.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unser Onlineshop\",\"item\":\"https:\\\/\\\/zauner.at\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Englischer Teekuchen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"name\":\"Konditorei Zauner\",\"description\":\"Konditorei\",\"publisher\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zauner.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\",\"name\":\"Konditorei Zauner\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"width\":160,\"height\":142,\"caption\":\"Konditorei Zauner\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\\\/\",\"https:\\\/\\\/www.instagram.com\\\/zaunerkaffeekonditorei\\\/\",\"https:\\\/\\\/at.linkedin.com\\\/company\\\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Englischer Teekuchen - fruchtig und aromatisch","description":"Genie\u00dfen Sie den Englischen Teekuchen von Zauner \u2013 saftig, fruchtig und mit feinsten Zutaten gebacken. Perfekt zum Tee oder Kaffee!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zauner.at\/cz\/product-2\/englischer-teekuchen\/","og_locale":"cs_CZ","og_type":"article","og_title":"Englischer Teekuchen - fruchtig und aromatisch","og_description":"Genie\u00dfen Sie den Englischen Teekuchen von Zauner \u2013 saftig, fruchtig und mit feinsten Zutaten gebacken. Perfekt zum Tee oder Kaffee!","og_url":"https:\/\/zauner.at\/cz\/product-2\/englischer-teekuchen\/","og_site_name":"Zauner","article_publisher":"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","article_modified_time":"2026-05-11T08:13:49+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/zauner.at\/wp-content\/uploads\/2024\/09\/Englischer-Teekuchen.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zauner.at\/produkt\/englischer-teekuchen\/","url":"https:\/\/zauner.at\/produkt\/englischer-teekuchen\/","name":"Englischer Teekuchen - fruchtig und aromatisch","isPartOf":{"@id":"https:\/\/zauner.at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zauner.at\/produkt\/englischer-teekuchen\/#primaryimage"},"image":{"@id":"https:\/\/zauner.at\/produkt\/englischer-teekuchen\/#primaryimage"},"thumbnailUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2024\/09\/Englischer-Teekuchen.jpg","datePublished":"2011-09-08T09:36:49+00:00","dateModified":"2026-05-11T08:13:49+00:00","description":"Genie\u00dfen Sie den Englischen Teekuchen von Zauner \u2013 saftig, fruchtig und mit feinsten Zutaten gebacken. Perfekt zum Tee oder Kaffee!","breadcrumb":{"@id":"https:\/\/zauner.at\/produkt\/englischer-teekuchen\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zauner.at\/produkt\/englischer-teekuchen\/"]}]},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zauner.at\/produkt\/englischer-teekuchen\/#primaryimage","url":"https:\/\/zauner.at\/wp-content\/uploads\/2024\/09\/Englischer-Teekuchen.jpg","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2024\/09\/Englischer-Teekuchen.jpg","width":1600,"height":1600,"caption":"Englischer Teekuchen"},{"@type":"BreadcrumbList","@id":"https:\/\/zauner.at\/produkt\/englischer-teekuchen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zauner.at\/"},{"@type":"ListItem","position":2,"name":"Unser Onlineshop","item":"https:\/\/zauner.at\/shop\/"},{"@type":"ListItem","position":3,"name":"Englischer Teekuchen"}]},{"@type":"WebSite","@id":"https:\/\/zauner.at\/#website","url":"https:\/\/zauner.at\/","name":"Cukr\u00e1rna Zauner","description":"Cukrovinky","publisher":{"@id":"https:\/\/zauner.at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zauner.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/zauner.at\/#organization","name":"Cukr\u00e1rna Zauner","url":"https:\/\/zauner.at\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/","url":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","width":160,"height":142,"caption":"Konditorei Zauner"},"image":{"@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","https:\/\/www.instagram.com\/zaunerkaffeekonditorei\/","https:\/\/at.linkedin.com\/company\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header"]}]}},"_links":{"self":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product\/213893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/comments?post=213893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/media\/211531"}],"wp:attachment":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/media?parent=213893"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_brand?post=213893"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_cat?post=213893"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_tag?post=213893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}