{"id":213804,"date":"2011-07-19T15:32:07","date_gmt":"2011-07-19T13:32:07","guid":{"rendered":"https:\/\/zauner.at\/produkt\/himbeer-truffel-bitterschokolade-100g\/"},"modified":"2026-04-29T13:15:08","modified_gmt":"2026-04-29T11:15:08","slug":"himbeer-truffel-bitterschokolade-100g","status":"publish","type":"product","link":"https:\/\/zauner.at\/cz\/produkt\/himbeer-truffel-bitterschokolade-100g\/","title":{"rendered":"Himbeer-Tr\u00fcffel (Edelbitter)"},"content":{"rendered":"<p>Von Hand gegossen und gef\u00fcllt.<\/p>\n<p>Trvanlivost a\u017e dva m\u011bs\u00edce.<\/p>\n<p>Allergene: Soja (F), Milch (G)<\/p>","protected":false},"excerpt":{"rendered":"<p>Zarte Edelbitterschokolade mit feinster Himbeer-Tr\u00fcffel-F\u00fcllung, ca. 100 g<\/p>","protected":false},"featured_media":202282,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[104],"product_tag":[118,336,120,337,127,338,143,154,329,330,331,333,334,335],"class_list":{"0":"post-213804","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-schokolade","7":"product_tag-bad-ischl","8":"product_tag-schoko","9":"product_tag-geschenk","10":"product_tag-schokoladentafel","11":"product_tag-schokolade","12":"product_tag-zarte-schokolade","13":"product_tag-zauner-bad-ischl","14":"product_tag-zauner","15":"product_tag-feine-schokolade","16":"product_tag-hofzuckerbaeckerei","17":"product_tag-kuk","18":"product_tag-oberoesterreich","19":"product_tag-onlineshop","20":"product_tag-salzkammergut","22":"first","23":"instock","24":"taxable","25":"shipping-taxable","26":"purchasable","27":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Himbeer-Tr\u00fcffel (Edelbitter) - Zauner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zauner.at\/cz\/product-2\/himbeer-truffel-bitterschokolade-100g\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Himbeer-Tr\u00fcffel (Edelbitter) - Zauner\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zauner.at\/cz\/product-2\/himbeer-truffel-bitterschokolade-100g\/\" \/>\n<meta property=\"og:site_name\" content=\"Zauner\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T11:15:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zauner.at\/wp-content\/uploads\/2024\/08\/Schokolade-Himbeere-Trueffel-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1601\" \/>\n\t<meta property=\"og:image:height\" content=\"1601\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/himbeer-truffel-bitterschokolade-100g\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/himbeer-truffel-bitterschokolade-100g\\\/\",\"name\":\"Himbeer-Tr\u00fcffel (Edelbitter) - Zauner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/himbeer-truffel-bitterschokolade-100g\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/himbeer-truffel-bitterschokolade-100g\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Schokolade-Himbeere-Trueffel-1.jpg\",\"datePublished\":\"2011-07-19T13:32:07+00:00\",\"dateModified\":\"2026-04-29T11:15:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/himbeer-truffel-bitterschokolade-100g\\\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zauner.at\\\/produkt\\\/himbeer-truffel-bitterschokolade-100g\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/himbeer-truffel-bitterschokolade-100g\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Schokolade-Himbeere-Trueffel-1.jpg\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Schokolade-Himbeere-Trueffel-1.jpg\",\"width\":1601,\"height\":1601,\"caption\":\"Schokolade-Himbeere-Tr\u00fcffel zarte Edelbitterschokolade mit feinster Himbeer-Tr\u00fcffel-F\u00fcllung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/himbeer-truffel-bitterschokolade-100g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zauner.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unser Onlineshop\",\"item\":\"https:\\\/\\\/zauner.at\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Himbeer-Tr\u00fcffel (Edelbitter)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"name\":\"Konditorei Zauner\",\"description\":\"Konditorei\",\"publisher\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zauner.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\",\"name\":\"Konditorei Zauner\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"width\":160,\"height\":142,\"caption\":\"Konditorei Zauner\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\\\/\",\"https:\\\/\\\/www.instagram.com\\\/zaunerkaffeekonditorei\\\/\",\"https:\\\/\\\/at.linkedin.com\\\/company\\\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Himbeer-Tr\u00fcffel (Edelbitter) - Zauner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zauner.at\/cz\/product-2\/himbeer-truffel-bitterschokolade-100g\/","og_locale":"cs_CZ","og_type":"article","og_title":"Himbeer-Tr\u00fcffel (Edelbitter) - Zauner","og_url":"https:\/\/zauner.at\/cz\/product-2\/himbeer-truffel-bitterschokolade-100g\/","og_site_name":"Zauner","article_publisher":"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","article_modified_time":"2026-04-29T11:15:08+00:00","og_image":[{"width":1601,"height":1601,"url":"https:\/\/zauner.at\/wp-content\/uploads\/2024\/08\/Schokolade-Himbeere-Trueffel-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zauner.at\/produkt\/himbeer-truffel-bitterschokolade-100g\/","url":"https:\/\/zauner.at\/produkt\/himbeer-truffel-bitterschokolade-100g\/","name":"Himbeer-Tr\u00fcffel (Edelbitter) - Zauner","isPartOf":{"@id":"https:\/\/zauner.at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zauner.at\/produkt\/himbeer-truffel-bitterschokolade-100g\/#primaryimage"},"image":{"@id":"https:\/\/zauner.at\/produkt\/himbeer-truffel-bitterschokolade-100g\/#primaryimage"},"thumbnailUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2024\/08\/Schokolade-Himbeere-Trueffel-1.jpg","datePublished":"2011-07-19T13:32:07+00:00","dateModified":"2026-04-29T11:15:08+00:00","breadcrumb":{"@id":"https:\/\/zauner.at\/produkt\/himbeer-truffel-bitterschokolade-100g\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zauner.at\/produkt\/himbeer-truffel-bitterschokolade-100g\/"]}]},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zauner.at\/produkt\/himbeer-truffel-bitterschokolade-100g\/#primaryimage","url":"https:\/\/zauner.at\/wp-content\/uploads\/2024\/08\/Schokolade-Himbeere-Trueffel-1.jpg","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2024\/08\/Schokolade-Himbeere-Trueffel-1.jpg","width":1601,"height":1601,"caption":"Schokolade-Himbeere-Tr\u00fcffel zarte Edelbitterschokolade mit feinster Himbeer-Tr\u00fcffel-F\u00fcllung"},{"@type":"BreadcrumbList","@id":"https:\/\/zauner.at\/produkt\/himbeer-truffel-bitterschokolade-100g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zauner.at\/"},{"@type":"ListItem","position":2,"name":"Unser Onlineshop","item":"https:\/\/zauner.at\/shop\/"},{"@type":"ListItem","position":3,"name":"Himbeer-Tr\u00fcffel (Edelbitter)"}]},{"@type":"WebSite","@id":"https:\/\/zauner.at\/#website","url":"https:\/\/zauner.at\/","name":"Cukr\u00e1rna Zauner","description":"Cukrovinky","publisher":{"@id":"https:\/\/zauner.at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zauner.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/zauner.at\/#organization","name":"Cukr\u00e1rna Zauner","url":"https:\/\/zauner.at\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/","url":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","width":160,"height":142,"caption":"Konditorei Zauner"},"image":{"@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","https:\/\/www.instagram.com\/zaunerkaffeekonditorei\/","https:\/\/at.linkedin.com\/company\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header"]}]}},"_links":{"self":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product\/213804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/comments?post=213804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/media\/202282"}],"wp:attachment":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/media?parent=213804"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_brand?post=213804"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_cat?post=213804"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_tag?post=213804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}