{"id":213688,"date":"2017-07-16T10:17:41","date_gmt":"2017-07-16T08:17:41","guid":{"rendered":"https:\/\/zauner.at\/produkt\/das-grobe-k-u-k-mehlspeisenbuch\/"},"modified":"2026-08-06T11:13:19","modified_gmt":"2026-08-06T09:13:19","slug":"kniha-o-skvelem-dezertu-kuk","status":"publish","type":"product","link":"https:\/\/zauner.at\/cz\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/","title":{"rendered":"Velk\u00e1 c\u00edsa\u0159sk\u00e1 a kr\u00e1lovsk\u00e1 kniha dezert\u016f"},"content":{"rendered":"<p>Cukr\u00e1rna Zauner je jednou z t\u011bch instituc\u00ed v Rakousku, kter\u00e9 zn\u00e1 ka\u017ed\u00fd. Budova Zauner je prodchnuta histori\u00ed a tradic\u00ed.<br \/>\nZde se s p\u00e9\u010d\u00ed a l\u00e1skou p\u011bstuje rakousk\u00e1 kav\u00e1rensk\u00e1 kultura. V pek\u00e1rn\u011b vznikaj\u00ed sv\u011btozn\u00e1m\u00e9 pe\u010divo, kter\u00e9<br \/>\nTehdy stejn\u011b jako dnes, t\u011b\u0161\u00ed a inspiruje lidi. Josef Zauner nejen odhaluje origin\u00e1ln\u00ed recepty, ale tak\u00e9 se s n\u00e1mi d\u011bl\u00ed o mnoho sv\u00fdch vlastn\u00edch.<br \/>\nPe\u010dliv\u011b p\u0159epracov\u00e1no a p\u0159izp\u016fsobeno nov\u00e9 kuchyni.<\/p>\n<p>Kniha m\u00e1 184 stran, pevnou vazbu, 19 x 25,5 cm.<\/p>","protected":false},"excerpt":{"rendered":"<p>Dlouho o\u010dek\u00e1van\u00e1 kniha Josefa Zaunera s jeho nejlep\u0161\u00edmi recepty!<\/p>","protected":false},"featured_media":217571,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[107,108],"product_tag":[722,725,827,829,830,900,122,901,331,1293,718,719,721],"class_list":["post-213688","product","type-product","status-publish","has-post-thumbnail","product_cat-geschenke-gutscheine","product_cat-buecher","product_tag-mehlspeisen","product_tag-rezepte","product_tag-mehlspeisenbuch","product_tag-oesterreichische-mehlspeisen","product_tag-servustv","product_tag-backtradition","product_tag-konditorei-zauner","product_tag-kochrezepte","product_tag-kuk","product_tag-k-u-k-mehlspeisenbuch","product_tag-backbuch","product_tag-josef-zauner","product_tag-kochbuch","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zauner Mehlspeisenbuch \u00bb Kaiserliche Rezepte!<\/title>\n<meta name=\"description\" content=\"Originalrezepte aus der k.u.k. Zeit \u2013 das gro\u00dfe Mehlspeisenbuch von Zauner bringt \u00f6sterreichische Backkunst in Ihre K\u00fcche! Jetzt sichern.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zauner.at\/cz\/product-2\/kniha-o-skvelem-dezertu-kuk\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zauner Mehlspeisenbuch \u00bb Kaiserliche Rezepte!\" \/>\n<meta property=\"og:description\" content=\"Originalrezepte aus der k.u.k. Zeit \u2013 das gro\u00dfe Mehlspeisenbuch von Zauner bringt \u00f6sterreichische Backkunst in Ihre K\u00fcche! Jetzt sichern.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zauner.at\/cz\/product-2\/kniha-o-skvelem-dezertu-kuk\/\" \/>\n<meta property=\"og:site_name\" content=\"Zauner\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-06T09:13:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zauner.at\/wp-content\/uploads\/2017\/07\/konditorei-zauner-produkt-geschenke-buecher-mehlspeisenbuch-1200x1200-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/das-grosse-k-u-k-mehlspeisenbuch\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/das-grosse-k-u-k-mehlspeisenbuch\\\/\",\"name\":\"Zauner Mehlspeisenbuch \u00bb Kaiserliche Rezepte!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/das-grosse-k-u-k-mehlspeisenbuch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/das-grosse-k-u-k-mehlspeisenbuch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/konditorei-zauner-produkt-geschenke-buecher-mehlspeisenbuch-1200x1200-1.jpg\",\"datePublished\":\"2017-07-16T08:17:41+00:00\",\"dateModified\":\"2026-08-06T09:13:19+00:00\",\"description\":\"Originalrezepte aus der k.u.k. Zeit \u2013 das gro\u00dfe Mehlspeisenbuch von Zauner bringt \u00f6sterreichische Backkunst in Ihre K\u00fcche! Jetzt sichern.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/das-grosse-k-u-k-mehlspeisenbuch\\\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zauner.at\\\/produkt\\\/das-grosse-k-u-k-mehlspeisenbuch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/das-grosse-k-u-k-mehlspeisenbuch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/konditorei-zauner-produkt-geschenke-buecher-mehlspeisenbuch-1200x1200-1.jpg\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/konditorei-zauner-produkt-geschenke-buecher-mehlspeisenbuch-1200x1200-1.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Buch \\\"Das gro\u00dfe k.u.k. Mehlspeisenbuch\\\" von Josef Zauner\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/das-grosse-k-u-k-mehlspeisenbuch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zauner.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unser Onlineshop\",\"item\":\"https:\\\/\\\/zauner.at\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Das gro\u00dfe k.u.k. Mehlspeisenbuch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"name\":\"Konditorei Zauner\",\"description\":\"Konditorei\",\"publisher\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zauner.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\",\"name\":\"Konditorei Zauner\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"width\":160,\"height\":142,\"caption\":\"Konditorei Zauner\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\\\/\",\"https:\\\/\\\/www.instagram.com\\\/zaunerkaffeekonditorei\\\/\",\"https:\\\/\\\/at.linkedin.com\\\/company\\\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zaunerova cukr\u00e1\u0159sk\u00e1 kniha \u00bb C\u00edsa\u0159sk\u00e9 recepty!","description":"Origin\u00e1ln\u00ed recepty z rakousko-uhersk\u00e9 \u00e9ry \u2013 Zaunerova obs\u00e1hl\u00e1 kniha o cukr\u00e1\u0159\u00edch p\u0159in\u00e1\u0161\u00ed rakousk\u00e9 peka\u0159sk\u00e9 um\u011bn\u00ed do va\u0161\u00ed kuchyn\u011b! Po\u0159i\u010fte si tu svou hned te\u010f.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zauner.at\/cz\/product-2\/kniha-o-skvelem-dezertu-kuk\/","og_locale":"cs_CZ","og_type":"article","og_title":"Zauner Mehlspeisenbuch \u00bb Kaiserliche Rezepte!","og_description":"Originalrezepte aus der k.u.k. Zeit \u2013 das gro\u00dfe Mehlspeisenbuch von Zauner bringt \u00f6sterreichische Backkunst in Ihre K\u00fcche! Jetzt sichern.","og_url":"https:\/\/zauner.at\/cz\/product-2\/kniha-o-skvelem-dezertu-kuk\/","og_site_name":"Zauner","article_publisher":"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","article_modified_time":"2026-08-06T09:13:19+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/zauner.at\/wp-content\/uploads\/2017\/07\/konditorei-zauner-produkt-geschenke-buecher-mehlspeisenbuch-1200x1200-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zauner.at\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/","url":"https:\/\/zauner.at\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/","name":"Zaunerova cukr\u00e1\u0159sk\u00e1 kniha \u00bb C\u00edsa\u0159sk\u00e9 recepty!","isPartOf":{"@id":"https:\/\/zauner.at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zauner.at\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/#primaryimage"},"image":{"@id":"https:\/\/zauner.at\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/#primaryimage"},"thumbnailUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2017\/07\/konditorei-zauner-produkt-geschenke-buecher-mehlspeisenbuch-1200x1200-1.jpg","datePublished":"2017-07-16T08:17:41+00:00","dateModified":"2026-08-06T09:13:19+00:00","description":"Origin\u00e1ln\u00ed recepty z rakousko-uhersk\u00e9 \u00e9ry \u2013 Zaunerova obs\u00e1hl\u00e1 kniha o cukr\u00e1\u0159\u00edch p\u0159in\u00e1\u0161\u00ed rakousk\u00e9 peka\u0159sk\u00e9 um\u011bn\u00ed do va\u0161\u00ed kuchyn\u011b! Po\u0159i\u010fte si tu svou hned te\u010f.","breadcrumb":{"@id":"https:\/\/zauner.at\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zauner.at\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/"]}]},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zauner.at\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/#primaryimage","url":"https:\/\/zauner.at\/wp-content\/uploads\/2017\/07\/konditorei-zauner-produkt-geschenke-buecher-mehlspeisenbuch-1200x1200-1.jpg","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2017\/07\/konditorei-zauner-produkt-geschenke-buecher-mehlspeisenbuch-1200x1200-1.jpg","width":1200,"height":1200,"caption":"Buch \"Das gro\u00dfe k.u.k. Mehlspeisenbuch\" von Josef Zauner"},{"@type":"BreadcrumbList","@id":"https:\/\/zauner.at\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zauner.at\/"},{"@type":"ListItem","position":2,"name":"Unser Onlineshop","item":"https:\/\/zauner.at\/shop\/"},{"@type":"ListItem","position":3,"name":"Das gro\u00dfe k.u.k. Mehlspeisenbuch"}]},{"@type":"WebSite","@id":"https:\/\/zauner.at\/#website","url":"https:\/\/zauner.at\/","name":"Cukr\u00e1rna Zauner","description":"Cukrovinky","publisher":{"@id":"https:\/\/zauner.at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zauner.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/zauner.at\/#organization","name":"Cukr\u00e1rna Zauner","url":"https:\/\/zauner.at\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/","url":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","width":160,"height":142,"caption":"Konditorei Zauner"},"image":{"@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","https:\/\/www.instagram.com\/zaunerkaffeekonditorei\/","https:\/\/at.linkedin.com\/company\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header"]}]}},"_links":{"self":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product\/213688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/comments?post=213688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/media\/217571"}],"wp:attachment":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/media?parent=213688"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_brand?post=213688"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_cat?post=213688"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_tag?post=213688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}