{"id":213688,"date":"2017-07-16T10:17:41","date_gmt":"2017-07-16T08:17:41","guid":{"rendered":"https:\/\/zauner.at\/produkt\/das-grobe-k-u-k-mehlspeisenbuch\/"},"modified":"2026-05-13T12:01:34","modified_gmt":"2026-05-13T10:01:34","slug":"das-grosse-k-u-k-mehlspeisenbuch","status":"publish","type":"product","link":"https:\/\/zauner.at\/cz\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/","title":{"rendered":"Velk\u00e1 c\u00edsa\u0159sk\u00e1 a kr\u00e1lovsk\u00e1 kniha dezert\u016f"},"content":{"rendered":"<p>Die Konditorei Zauner ist eine der Institutionen in \u00d6sterreich, die jeder kennt. Das Haus Zauner ist voll Geschichte und Tradition.<br \/>\nHier wird die \u00f6sterreichische Kaffeehauskultur mit Sorgfalt und Liebe gepflegt. In der Backstube werden weltber\u00fchmte Mehlspeisen kreiert, die<br \/>\ndamals wie heute die Menschen erfreuen und begeistern. Josef Zauner verr\u00e4t nicht nur Originalrezepturen, er hat auch viele seiner eigenen Rezepte<br \/>\nbehutsam \u00fcberarbeitet, der neuen K\u00fcche angepasst.<\/p>\n<p>Das Buch hat 184 Seiten, Hardcover, 19 x 25,5 cm.<\/p>","protected":false},"excerpt":{"rendered":"<p>Das lang erwartete Buch von Josef Zauner mit seinen besten Rezepten!<\/p>","protected":false},"featured_media":217571,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[107,108],"product_tag":[722,725,827,829,830,900,122,901,331,1293,718,719,721],"class_list":{"0":"post-213688","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-geschenke-gutscheine","7":"product_cat-buecher","8":"product_tag-mehlspeisen","9":"product_tag-rezepte","10":"product_tag-mehlspeisenbuch","11":"product_tag-oesterreichische-mehlspeisen","12":"product_tag-servustv","13":"product_tag-backtradition","14":"product_tag-konditorei-zauner","15":"product_tag-kochrezepte","16":"product_tag-kuk","17":"product_tag-k-u-k-mehlspeisenbuch","18":"product_tag-backbuch","19":"product_tag-josef-zauner","20":"product_tag-kochbuch","22":"first","23":"instock","24":"taxable","25":"shipping-taxable","26":"purchasable","27":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zauner Mehlspeisenbuch \u00bb Kaiserliche Rezepte!<\/title>\n<meta name=\"description\" content=\"Originalrezepte aus der k.u.k. Zeit \u2013 das gro\u00dfe Mehlspeisenbuch von Zauner bringt \u00f6sterreichische Backkunst in Ihre K\u00fcche! Jetzt sichern.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zauner.at\/cz\/product-2\/das-grosse-k-u-k-mehlspeisenbuch\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zauner Mehlspeisenbuch \u00bb Kaiserliche Rezepte!\" \/>\n<meta property=\"og:description\" content=\"Originalrezepte aus der k.u.k. Zeit \u2013 das gro\u00dfe Mehlspeisenbuch von Zauner bringt \u00f6sterreichische Backkunst in Ihre K\u00fcche! Jetzt sichern.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zauner.at\/cz\/product-2\/das-grosse-k-u-k-mehlspeisenbuch\/\" \/>\n<meta property=\"og:site_name\" content=\"Zauner\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T10:01:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zauner.at\/wp-content\/uploads\/2017\/07\/konditorei-zauner-produkt-geschenke-buecher-mehlspeisenbuch-1200x1200-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/das-grosse-k-u-k-mehlspeisenbuch\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/das-grosse-k-u-k-mehlspeisenbuch\\\/\",\"name\":\"Zauner Mehlspeisenbuch \u00bb Kaiserliche Rezepte!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/das-grosse-k-u-k-mehlspeisenbuch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/das-grosse-k-u-k-mehlspeisenbuch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/konditorei-zauner-produkt-geschenke-buecher-mehlspeisenbuch-1200x1200-1.jpg\",\"datePublished\":\"2017-07-16T08:17:41+00:00\",\"dateModified\":\"2026-05-13T10:01:34+00:00\",\"description\":\"Originalrezepte aus der k.u.k. Zeit \u2013 das gro\u00dfe Mehlspeisenbuch von Zauner bringt \u00f6sterreichische Backkunst in Ihre K\u00fcche! Jetzt sichern.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/das-grosse-k-u-k-mehlspeisenbuch\\\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zauner.at\\\/produkt\\\/das-grosse-k-u-k-mehlspeisenbuch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/das-grosse-k-u-k-mehlspeisenbuch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/konditorei-zauner-produkt-geschenke-buecher-mehlspeisenbuch-1200x1200-1.jpg\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/konditorei-zauner-produkt-geschenke-buecher-mehlspeisenbuch-1200x1200-1.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Buch \\\"Das gro\u00dfe k.u.k. Mehlspeisenbuch\\\" von Josef Zauner\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zauner.at\\\/produkt\\\/das-grosse-k-u-k-mehlspeisenbuch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zauner.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unser Onlineshop\",\"item\":\"https:\\\/\\\/zauner.at\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Das gro\u00dfe k.u.k. Mehlspeisenbuch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"name\":\"Konditorei Zauner\",\"description\":\"Konditorei\",\"publisher\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zauner.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\",\"name\":\"Konditorei Zauner\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"width\":160,\"height\":142,\"caption\":\"Konditorei Zauner\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\\\/\",\"https:\\\/\\\/www.instagram.com\\\/zaunerkaffeekonditorei\\\/\",\"https:\\\/\\\/at.linkedin.com\\\/company\\\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zauner Mehlspeisenbuch \u00bb Kaiserliche Rezepte!","description":"Originalrezepte aus der k.u.k. Zeit \u2013 das gro\u00dfe Mehlspeisenbuch von Zauner bringt \u00f6sterreichische Backkunst in Ihre K\u00fcche! Jetzt sichern.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zauner.at\/cz\/product-2\/das-grosse-k-u-k-mehlspeisenbuch\/","og_locale":"cs_CZ","og_type":"article","og_title":"Zauner Mehlspeisenbuch \u00bb Kaiserliche Rezepte!","og_description":"Originalrezepte aus der k.u.k. Zeit \u2013 das gro\u00dfe Mehlspeisenbuch von Zauner bringt \u00f6sterreichische Backkunst in Ihre K\u00fcche! Jetzt sichern.","og_url":"https:\/\/zauner.at\/cz\/product-2\/das-grosse-k-u-k-mehlspeisenbuch\/","og_site_name":"Zauner","article_publisher":"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","article_modified_time":"2026-05-13T10:01:34+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/zauner.at\/wp-content\/uploads\/2017\/07\/konditorei-zauner-produkt-geschenke-buecher-mehlspeisenbuch-1200x1200-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zauner.at\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/","url":"https:\/\/zauner.at\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/","name":"Zauner Mehlspeisenbuch \u00bb Kaiserliche Rezepte!","isPartOf":{"@id":"https:\/\/zauner.at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zauner.at\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/#primaryimage"},"image":{"@id":"https:\/\/zauner.at\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/#primaryimage"},"thumbnailUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2017\/07\/konditorei-zauner-produkt-geschenke-buecher-mehlspeisenbuch-1200x1200-1.jpg","datePublished":"2017-07-16T08:17:41+00:00","dateModified":"2026-05-13T10:01:34+00:00","description":"Originalrezepte aus der k.u.k. Zeit \u2013 das gro\u00dfe Mehlspeisenbuch von Zauner bringt \u00f6sterreichische Backkunst in Ihre K\u00fcche! Jetzt sichern.","breadcrumb":{"@id":"https:\/\/zauner.at\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zauner.at\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/"]}]},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zauner.at\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/#primaryimage","url":"https:\/\/zauner.at\/wp-content\/uploads\/2017\/07\/konditorei-zauner-produkt-geschenke-buecher-mehlspeisenbuch-1200x1200-1.jpg","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2017\/07\/konditorei-zauner-produkt-geschenke-buecher-mehlspeisenbuch-1200x1200-1.jpg","width":1200,"height":1200,"caption":"Buch \"Das gro\u00dfe k.u.k. Mehlspeisenbuch\" von Josef Zauner"},{"@type":"BreadcrumbList","@id":"https:\/\/zauner.at\/produkt\/das-grosse-k-u-k-mehlspeisenbuch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zauner.at\/"},{"@type":"ListItem","position":2,"name":"Unser Onlineshop","item":"https:\/\/zauner.at\/shop\/"},{"@type":"ListItem","position":3,"name":"Das gro\u00dfe k.u.k. Mehlspeisenbuch"}]},{"@type":"WebSite","@id":"https:\/\/zauner.at\/#website","url":"https:\/\/zauner.at\/","name":"Cukr\u00e1rna Zauner","description":"Cukrovinky","publisher":{"@id":"https:\/\/zauner.at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zauner.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/zauner.at\/#organization","name":"Cukr\u00e1rna Zauner","url":"https:\/\/zauner.at\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/","url":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","width":160,"height":142,"caption":"Konditorei Zauner"},"image":{"@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","https:\/\/www.instagram.com\/zaunerkaffeekonditorei\/","https:\/\/at.linkedin.com\/company\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header"]}]}},"_links":{"self":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product\/213688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/comments?post=213688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/media\/217571"}],"wp:attachment":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/media?parent=213688"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_brand?post=213688"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_cat?post=213688"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/product_tag?post=213688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}