{"id":541,"date":"2021-06-28T14:46:29","date_gmt":"2021-06-28T12:46:29","guid":{"rendered":"https:\/\/zauner.at\/?p=541"},"modified":"2024-08-21T11:52:20","modified_gmt":"2024-08-21T09:52:20","slug":"zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet","status":"publish","type":"post","link":"https:\/\/zauner.at\/cz\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\/","title":{"rendered":"Zuckerb\u00e4ckermeister Josef Zauner wurde mit dem goldenen Ehrenzeichen des Landes Ober\u00f6sterreich ausgezeichnet!"},"content":{"rendered":"<p>Am 23.06.2021 wurde Josef Zauner, der die Geschichte der Bad Ischler k.u.k. Hofzuckerb\u00e4ckerei Zauner \u00fcber mehr als f\u00fcnf Jahrzehnte ma\u00dfgeblich pr\u00e4gte, von Landeshauptmann Thomas Stelzer im Linzer Redoutensaal mit dem goldenen Ehrenzeichen des Landes Ober\u00f6sterreich ausgezeichnet.<\/p>\n<p>\u201eDamit soll dem Lebenswerk von Josef Zauner, der die Konditorei Zauner zu einemOber\u00f6sterreichischen Vorzeigeunternehmen formte, unsere gr\u00f6\u00dfte Anerkennung ausgesprochen werden\u201c, so Landeshauptmann Thomas Stelzer.<\/p>\n<p>Josef Zauner, der neben der \u00f6sterreichischen auch die deutsche Meisterpr\u00fcfung ablegte, durch zahlreiche Auslandseins\u00e4tze internationale Erfahrung sammeln konnte und als Fernsehkonditor derSendung \u201eH\u00e4ferlgucker\u201c gl\u00e4nzte, steht inmitten eines bewegten Lebens: In Japan unterrichtet er ander bekannten japanischen Konditoreifachschule \u201cJapan Cake- and Confiserie-College\u201d, ist seit 1988Gastprofessor dieser Schule und blickt gleichzeitig auf 55 erfolgreiche Jahre im Hause Zauner zur\u00fcck.<\/p>\n<p>\u201eSehr stolz stimmt mich, einen Betrieb geformt zu haben, der weit \u00fcber unsere Grenzen hinaus bekannt ist. Gleichzeit f\u00fchle ich mich sehr privilegiert, dass mir dies gelungen ist indem ich t\u00e4glich meiner Leidenschaft \u2013 dem klassischen \u00f6sterreichischen Konditorhandwerk \u2013 nachgegangen bin\u201c,Josef Zauner.<\/p>\n<p>Josef Zauner zeichnet sich im Laufe seiner Berufskarriere f\u00fcr die Ausbildung von mehr als 150 Konditorlehrlingen verantwortlich, die im Hause Zauner die gesamte Palette der \u00f6sterreichischen Konditorkunst erlernen k\u00f6nnen. Die Geschicke im traditionsreichen Familienunternehmen hat Josef Zauner im Herbst des vergangenen Jahres an seinen Sohn Philipp \u00fcbergeben, der die Konditorei in die mittlerweile 7. Generation f\u00fchrt. Der hochgesch\u00e4tzte Seniorchef des Hauses bleibt dem Unternehmen jedoch auch in Zukunft erhalten: \u201eDer Zauner ist und bleibt meine Passion, f\u00fcr einenerfolgreichen Familienbetrieb ben\u00f6tigt es das Zusammenspiel mehrerer Generationen. Ich bin froh, dass der \u00dcbergang von einer Generation auf die andere in unserem Falle sehr gut funktioniert\u201c, Zauner.<\/p>","protected":false},"excerpt":{"rendered":"<p>Am 23.06.2021 wurde Josef Zauner, der die Geschichte der Bad Ischler k.u.k. Hofzuckerb\u00e4ckerei Zauner \u00fcber mehr als f\u00fcnf Jahrzehnte ma\u00dfgeblich pr\u00e4gte, von Landeshauptmann Thomas Stelzer im Linzer Redoutensaal mit dem goldenen Ehrenzeichen des Landes Ober\u00f6sterreich ausgezeichnet. \u201eDamit soll dem Lebenswerk von Josef Zauner, der die Konditorei Zauner zu einemOber\u00f6sterreichischen Vorzeigeunternehmen formte, unsere gr\u00f6\u00dfte Anerkennung ausgesprochen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":443,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[576],"tags":[],"class_list":["post-541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zuckerb\u00e4ckermeister Josef Zauner wurde mit dem goldenen Ehrenzeichen des Landes Ober\u00f6sterreich ausgezeichnet! - Zauner<\/title>\n<meta name=\"description\" content=\"Josef Zauner erh\u00e4lt das Goldene Ehrenzeichen des Landes Ober\u00f6sterreich \u2013 eine besondere Anerkennung f\u00fcr sein Lebenswerk &amp; seine Meisterkunst.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zauner.at\/cz\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zuckerb\u00e4ckermeister Josef Zauner wurde mit dem goldenen Ehrenzeichen des Landes Ober\u00f6sterreich ausgezeichnet! - Zauner\" \/>\n<meta property=\"og:description\" content=\"Josef Zauner erh\u00e4lt das Goldene Ehrenzeichen des Landes Ober\u00f6sterreich \u2013 eine besondere Anerkennung f\u00fcr sein Lebenswerk &amp; seine Meisterkunst.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zauner.at\/cz\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\/\" \/>\n<meta property=\"og:site_name\" content=\"Zauner\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-28T12:46:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-21T09:52:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zauner.at\/wp-content\/uploads\/2024\/06\/zauner-news-Thomas-Stelzer-Josef-Zauner-705x470-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"705\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yvonne\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napsal(a)\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yvonne\" \/>\n\t<meta name=\"twitter:label2\" content=\"Odhadovan\u00e1 doba \u010dten\u00ed\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/zauner.at\\\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\\\/\"},\"author\":{\"name\":\"Yvonne\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/person\\\/5316bb2b3fa5f0c0ebacb7426f8b8d42\"},\"headline\":\"Zuckerb\u00e4ckermeister Josef Zauner wurde mit dem goldenen Ehrenzeichen des Landes Ober\u00f6sterreich ausgezeichnet!\",\"datePublished\":\"2021-06-28T12:46:29+00:00\",\"dateModified\":\"2024-08-21T09:52:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\\\/\"},\"wordCount\":294,\"publisher\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/zauner-news-Thomas-Stelzer-Josef-Zauner-705x470-1.jpg\",\"articleSection\":[\"news\"],\"inLanguage\":\"cs\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zauner.at\\\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\\\/\",\"name\":\"Zuckerb\u00e4ckermeister Josef Zauner wurde mit dem goldenen Ehrenzeichen des Landes Ober\u00f6sterreich ausgezeichnet! - Zauner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/zauner-news-Thomas-Stelzer-Josef-Zauner-705x470-1.jpg\",\"datePublished\":\"2021-06-28T12:46:29+00:00\",\"dateModified\":\"2024-08-21T09:52:20+00:00\",\"description\":\"Josef Zauner erh\u00e4lt das Goldene Ehrenzeichen des Landes Ober\u00f6sterreich \u2013 eine besondere Anerkennung f\u00fcr sein Lebenswerk &amp; seine Meisterkunst.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\\\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zauner.at\\\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zauner.at\\\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/zauner-news-Thomas-Stelzer-Josef-Zauner-705x470-1.jpg\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/zauner-news-Thomas-Stelzer-Josef-Zauner-705x470-1.jpg\",\"width\":705,\"height\":470,\"caption\":\"Thomas Stelzer, Josef Zauner mit dem Verdienstkreuz des Landes O\u00d6\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zauner.at\\\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zauner.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zuckerb\u00e4ckermeister Josef Zauner wurde mit dem goldenen Ehrenzeichen des Landes Ober\u00f6sterreich ausgezeichnet!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#website\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"name\":\"Konditorei Zauner\",\"description\":\"Konditorei\",\"publisher\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zauner.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#organization\",\"name\":\"Konditorei Zauner\",\"url\":\"https:\\\/\\\/zauner.at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"contentUrl\":\"https:\\\/\\\/zauner.at\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zauner-logo.png\",\"width\":160,\"height\":142,\"caption\":\"Konditorei Zauner\"},\"image\":{\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\\\/\",\"https:\\\/\\\/www.instagram.com\\\/zaunerkaffeekonditorei\\\/\",\"https:\\\/\\\/at.linkedin.com\\\/company\\\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zauner.at\\\/#\\\/schema\\\/person\\\/5316bb2b3fa5f0c0ebacb7426f8b8d42\",\"name\":\"Yvonne\",\"url\":\"https:\\\/\\\/zauner.at\\\/cz\\\/author\\\/yvan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zuckerb\u00e4ckermeister Josef Zauner wurde mit dem goldenen Ehrenzeichen des Landes Ober\u00f6sterreich ausgezeichnet! - Zauner","description":"Josef Zauner erh\u00e4lt das Goldene Ehrenzeichen des Landes Ober\u00f6sterreich \u2013 eine besondere Anerkennung f\u00fcr sein Lebenswerk &amp; seine Meisterkunst.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zauner.at\/cz\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\/","og_locale":"cs_CZ","og_type":"article","og_title":"Zuckerb\u00e4ckermeister Josef Zauner wurde mit dem goldenen Ehrenzeichen des Landes Ober\u00f6sterreich ausgezeichnet! - Zauner","og_description":"Josef Zauner erh\u00e4lt das Goldene Ehrenzeichen des Landes Ober\u00f6sterreich \u2013 eine besondere Anerkennung f\u00fcr sein Lebenswerk &amp; seine Meisterkunst.","og_url":"https:\/\/zauner.at\/cz\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\/","og_site_name":"Zauner","article_publisher":"https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","article_published_time":"2021-06-28T12:46:29+00:00","article_modified_time":"2024-08-21T09:52:20+00:00","og_image":[{"width":705,"height":470,"url":"https:\/\/zauner.at\/wp-content\/uploads\/2024\/06\/zauner-news-Thomas-Stelzer-Josef-Zauner-705x470-1.jpg","type":"image\/jpeg"}],"author":"Yvonne","twitter_card":"summary_large_image","twitter_misc":{"Napsal(a)":"Yvonne","Odhadovan\u00e1 doba \u010dten\u00ed":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/zauner.at\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\/#article","isPartOf":{"@id":"https:\/\/zauner.at\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\/"},"author":{"name":"Yvonne","@id":"https:\/\/zauner.at\/#\/schema\/person\/5316bb2b3fa5f0c0ebacb7426f8b8d42"},"headline":"Zuckerb\u00e4ckermeister Josef Zauner wurde mit dem goldenen Ehrenzeichen des Landes Ober\u00f6sterreich ausgezeichnet!","datePublished":"2021-06-28T12:46:29+00:00","dateModified":"2024-08-21T09:52:20+00:00","mainEntityOfPage":{"@id":"https:\/\/zauner.at\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\/"},"wordCount":294,"publisher":{"@id":"https:\/\/zauner.at\/#organization"},"image":{"@id":"https:\/\/zauner.at\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\/#primaryimage"},"thumbnailUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2024\/06\/zauner-news-Thomas-Stelzer-Josef-Zauner-705x470-1.jpg","articleSection":["news"],"inLanguage":"cs"},{"@type":"WebPage","@id":"https:\/\/zauner.at\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\/","url":"https:\/\/zauner.at\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\/","name":"Zuckerb\u00e4ckermeister Josef Zauner wurde mit dem goldenen Ehrenzeichen des Landes Ober\u00f6sterreich ausgezeichnet! - Zauner","isPartOf":{"@id":"https:\/\/zauner.at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zauner.at\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\/#primaryimage"},"image":{"@id":"https:\/\/zauner.at\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\/#primaryimage"},"thumbnailUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2024\/06\/zauner-news-Thomas-Stelzer-Josef-Zauner-705x470-1.jpg","datePublished":"2021-06-28T12:46:29+00:00","dateModified":"2024-08-21T09:52:20+00:00","description":"Josef Zauner erh\u00e4lt das Goldene Ehrenzeichen des Landes Ober\u00f6sterreich \u2013 eine besondere Anerkennung f\u00fcr sein Lebenswerk &amp; seine Meisterkunst.","breadcrumb":{"@id":"https:\/\/zauner.at\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zauner.at\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\/"]}]},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zauner.at\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\/#primaryimage","url":"https:\/\/zauner.at\/wp-content\/uploads\/2024\/06\/zauner-news-Thomas-Stelzer-Josef-Zauner-705x470-1.jpg","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2024\/06\/zauner-news-Thomas-Stelzer-Josef-Zauner-705x470-1.jpg","width":705,"height":470,"caption":"Thomas Stelzer, Josef Zauner mit dem Verdienstkreuz des Landes O\u00d6"},{"@type":"BreadcrumbList","@id":"https:\/\/zauner.at\/zuckerbaeckermeister-josef-zauner-wurde-mit-dem-goldenen-ehrenzeichen-des-landes-oberoesterreich-ausgezeichnet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zauner.at\/"},{"@type":"ListItem","position":2,"name":"Zuckerb\u00e4ckermeister Josef Zauner wurde mit dem goldenen Ehrenzeichen des Landes Ober\u00f6sterreich ausgezeichnet!"}]},{"@type":"WebSite","@id":"https:\/\/zauner.at\/#website","url":"https:\/\/zauner.at\/","name":"Cukr\u00e1rna Zauner","description":"Cukrovinky","publisher":{"@id":"https:\/\/zauner.at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zauner.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/zauner.at\/#organization","name":"Cukr\u00e1rna Zauner","url":"https:\/\/zauner.at\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/","url":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","contentUrl":"https:\/\/zauner.at\/wp-content\/uploads\/2025\/02\/zauner-logo.png","width":160,"height":142,"caption":"Konditorei Zauner"},"image":{"@id":"https:\/\/zauner.at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Konditorei-Kaffee-Zauner-Bad-Ischl-100057212599739\/","https:\/\/www.instagram.com\/zaunerkaffeekonditorei\/","https:\/\/at.linkedin.com\/company\/konditorei-kaffee-zauner?trk=public_profile_experience-group-header"]},{"@type":"Person","@id":"https:\/\/zauner.at\/#\/schema\/person\/5316bb2b3fa5f0c0ebacb7426f8b8d42","name":"Yvonne","url":"https:\/\/zauner.at\/cz\/author\/yvan\/"}]}},"_links":{"self":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/posts\/541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/comments?post=541"}],"version-history":[{"count":0,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/posts\/541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/media\/443"}],"wp:attachment":[{"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/media?parent=541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/categories?post=541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zauner.at\/cz\/wp-json\/wp\/v2\/tags?post=541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}